{"id":7582,"date":"2022-02-04T10:18:20","date_gmt":"2022-02-04T09:18:20","guid":{"rendered":"http:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-deluxe-residence-il-borgo\/"},"modified":"2025-06-23T11:31:14","modified_gmt":"2025-06-23T09:31:14","slug":"appartamento-bluette-residence-il-borgo","status":"publish","type":"page","link":"https:\/\/www.sardegnasummer.it\/en\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-bluette-residence-il-borgo\/","title":{"rendered":"Apartment Bluette Residence Il Borgo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7582\" class=\"elementor elementor-7582 elementor-5029\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66e5cdda elementor-section-height-min-height elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-items-middle wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"66e5cdda\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-34293c1b\" data-id=\"34293c1b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33148a7d elementor-heading-tablet__align-center animated-fast elementor-heading__align-center elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"33148a7d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.5.3 - 28-12-2021 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h6 class=\"elementor-heading-title elementor-size-default\">APARTMENT<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ee0c935 elementor-heading-tablet__align-center animated-fast elementor-heading__align-center elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5ee0c935\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">bluette<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f90b38 elementor-heading-tablet__align-center animated-fast elementor-heading__align-center elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7f90b38\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">residence il borgo - porto san paolo<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a2d0130\" data-id=\"a2d0130\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-441ce7a elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"441ce7a\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.5.3 - 28-12-2021 *\/\n.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"441ce7a\" data-elementor-lightbox-title=\"IL BORGO PSP9\" href=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/IL-BORGO-PSP9-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/IL-BORGO-PSP9-scaled-pk0e35khglgztbyhkj7qi7n3wn70kq2r0tuiow70kw.jpg\" alt=\"IL BORGO PSP9\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"441ce7a\" data-elementor-lightbox-title=\"IL BORGO PSP8\" href=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/IL-BORGO-PSP8-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/IL-BORGO-PSP8-scaled-pk0e3u0aeaeg76yzlts1b1h3cnuk4urrs6t5636s34.jpg\" alt=\"IL BORGO PSP8\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"441ce7a\" data-elementor-lightbox-title=\"IL BORGO PSP7\" href=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/IL-BORGO-PSP7-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/IL-BORGO-PSP7-scaled-pk0e4p0yntkwubpxkp6q3bnaydlo6v6wwgc607wsds.jpg\" alt=\"IL BORGO PSP7\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"441ce7a\" data-elementor-lightbox-title=\"IL BORGO PSP6\" href=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/IL-BORGO-PSP6-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/IL-BORGO-PSP6-scaled-pk0e5i5yjoosu8jlujs5qmaldbm1thelcgk7vspl0w.jpg\" alt=\"IL BORGO PSP6\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"441ce7a\" data-elementor-lightbox-title=\"IL BORGO PSP5\" href=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/IL-BORGO-PSP5-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/IL-BORGO-PSP5-scaled-pk0e6ad48preijen9vyytf6f6vr28eijgc4sa3jru8.jpg\" alt=\"IL BORGO PSP5\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"441ce7a\" href=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/IL-BORGO-PSP4-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/IL-BORGO-PSP4-scaled-pk0e79559l30g404mt05voeh64zn57clx49r1c47g0.jpg\" alt=\"\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"441ce7a\" href=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/IL-BORGO-PSP2-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/IL-BORGO-PSP2-scaled-pk0e9e7wu00iw4w64qbkk4y9vqfqoduljprke0xx9s.jpg\" alt=\"\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"441ce7a\" href=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/IL-BORGO-PSP15-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/IL-BORGO-PSP15-scaled-pk0eaczxuvc4tphnhncrme6buzobl6oo0hwj59icvk.jpg\" alt=\"\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"441ce7a\" href=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/IL-BORGO-PSP14-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/IL-BORGO-PSP14-scaled-pk0ebdnn9eqbei0ejl77tmxb10nmxdq75jcgv2004w.jpg\" alt=\"\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"441ce7a\" href=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/IL-BORGO-PSP13-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/IL-BORGO-PSP13-scaled-pk0ec6sn59u7eeu2tfsngxklfyo0jzxvljkiqmsss0.jpg\" alt=\"\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"441ce7a\" href=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/IL-BORGO-PSP12-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/IL-BORGO-PSP12-scaled-pk0eczxn14y3ebnr3ae3487vuwoe6m5k1jskm7llf4.jpg\" alt=\"\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"441ce7a\" href=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/IL-BORGO-PSP11-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/IL-BORGO-PSP11-scaled-pk0edxrtv68f0aallp0nlzoh8s1lvpvw67a1w67f74.jpg\" alt=\"\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"441ce7a\" href=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/IL-BORGO-PSP10-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/IL-BORGO-PSP10-scaled-pk0eetqcbjg5z106f2tyyrm5fvo35fermlgk7kw1bk.jpg\" alt=\"\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"441ce7a\" href=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/IL-BORGO-PSP1-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/IL-BORGO-PSP1-scaled-pk0efue1q2ucjtixh0of60d4lwnehmgarmwhxddokw.jpg\" alt=\"\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b007b56 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"1b007b56\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-265df2ee\" data-id=\"265df2ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-551fe6c elementor-widget elementor-widget-text-editor\" data-id=\"551fe6c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.5.3 - 28-12-2021 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<h1>Comfort and luxury in the center of Porto San Paolo<\/h1>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37778fd5 elementor-widget elementor-widget-text-editor\" data-id=\"37778fd5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"western\" lang=\"es-419\">Il Borgo di Porto San Paolo simply don\u2019t come any finer. Settled in the heart of this beautiful neighbourhood, this apartment is loved for its winning combination of elegance and luxury decoration inspired by the colors of the marine world&#8230; a wonderful and peaceful oasis overlooking Tavolara. Everything, just a few steps from the beach and services. Enjoy this bright and spacious apartment with your loved ones, with all the comfort of two bedrooms, fully equipped kitchen, large living room, two bathrooms with shower, two large terraces, one covered and furnished for outdoor dining with a relaxing view of the garden. It comes with air conditioning, washing machine, electric oven and microwave, to feel like home and make your vacation an unforgettable memory.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5eec233 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"5eec233\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-da15a21\" data-id=\"da15a21\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fea2f8f elementor-heading-tablet__align-center animated-fast elementor-heading__align-center elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"fea2f8f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">EQUIPMENT AND FACILITIES<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1793166e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"1793166e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-4b2b2758\" data-id=\"4b2b2758\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc37fcd elementor-widget elementor-widget-image\" data-id=\"fc37fcd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.5.3 - 28-12-2021 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"102\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/42-400x102.png\" class=\"attachment-maisonco-gallery-image size-maisonco-gallery-image\" alt=\"\" srcset=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/42-400x102.png 400w, https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/42-300x77.png 300w, https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/42-1024x262.png 1024w, https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/42-768x197.png 768w, https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/42-1536x393.png 1536w, https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2022\/02\/42.png 2000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ee70ab5 elementor-widget elementor-widget-text-editor\" data-id=\"3ee70ab5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>MAXIMUM OCCUPANCY 4 ADULTS + 2 CHILDREN<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-28c14893\" data-id=\"28c14893\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-319768a1 elementor-widget elementor-widget-image\" data-id=\"319768a1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/layers-pkor8y18yi8jh9qwy3harnsa7sp1s20g6c4t3blhf8.png\" title=\"layers\" alt=\"layers\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18bf312 elementor-widget elementor-widget-text-editor\" data-id=\"18bf312\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>ON THE FIRST FLOOR WITH TWO BATHROOMS<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-7815170c\" data-id=\"7815170c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b403f57 elementor-widget elementor-widget-image\" data-id=\"b403f57\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/terrace-2-pklc3eq5c92629pfoocd1g4tmp15n36hydaxop8tx0.png\" title=\"\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-617eebd elementor-widget elementor-widget-text-editor\" data-id=\"617eebd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>COVERED AND FURNISHED TERRACE WITH GARDEN VIEW<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-5587d86\" data-id=\"5587d86\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e015284 elementor-widget elementor-widget-image\" data-id=\"e015284\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/air-conditioning-pkorowcmya2qj0koshqcl4ux682bf4cg1aqhbdxxtg.png\" title=\"air-conditioning\" alt=\"air-conditioning\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-505b77c elementor-widget elementor-widget-text-editor\" data-id=\"505b77c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Air conditioning*\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-1f4db4d1\" data-id=\"1f4db4d1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50770370 elementor-widget elementor-widget-image\" data-id=\"50770370\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/134-pm1fgmiifbkakszqx4vh48193mzczcywhrjkycq5is.png\" title=\"134\" alt=\"134\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8b261c elementor-widget elementor-widget-text-editor\" data-id=\"c8b261c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>LCD AND SATELLITE TV\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-670203bd\" data-id=\"670203bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b9ae107 elementor-widget elementor-widget-image\" data-id=\"6b9ae107\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/oven-pkotx8m13i20v5vinpxe7d090u2qbsaiqy3izstjzo.png\" title=\"oven\" alt=\"oven\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a5f864c elementor-widget elementor-widget-text-editor\" data-id=\"5a5f864c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>ELECTRIC OVEN<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72ee0a6a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"72ee0a6a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-b56a19a\" data-id=\"b56a19a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a7a0b8 elementor-widget elementor-widget-image\" data-id=\"9a7a0b8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/dryer-pk99bst0p36r4gji36k2f2rzmxtixrdm23j5k01i7o.png\" title=\"dryer\" alt=\"dryer\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d5a78a elementor-widget elementor-widget-text-editor\" data-id=\"7d5a78a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>HAIR DRYER<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5dfab2c\" data-id=\"5dfab2c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e1ae60 elementor-widget elementor-widget-image\" data-id=\"7e1ae60\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/water-boiler-pk99i9wzs01v3r4w9zbjlfyayhwjyp31m5bkkmfvck.png\" title=\"water-boiler\" alt=\"water-boiler\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c04967 elementor-widget elementor-widget-text-editor\" data-id=\"1c04967\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00a0kettle for tea\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-27c8bd75\" data-id=\"27c8bd75\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-936969d elementor-widget elementor-widget-image\" data-id=\"936969d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/10-pk8yfu3us6m9q9w2vr4onzk9ylrd5jb46221657kvo.png\" title=\"10\" alt=\"10\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a5c388a elementor-widget elementor-widget-text-editor\" data-id=\"3a5c388a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>MICROWAVE OVEN<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-54bbbd37\" data-id=\"54bbbd37\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7039f8b elementor-widget elementor-widget-image\" data-id=\"7039f8b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/2-1-pk8xnsl6w48bd2mgmmrda2b7yrz5ilzeb9ejqyseic.png\" title=\"2\" alt=\"2\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cd4e1af elementor-widget elementor-widget-text-editor\" data-id=\"6cd4e1af\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>WASHING MACHINE<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-667198f6\" data-id=\"667198f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c3b45af elementor-widget elementor-widget-image\" data-id=\"4c3b45af\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/5-1-pk8ye9pje4h2do6012r2idsmbhhcbp37yawwdjj790.png\" title=\"5\" alt=\"5\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5591748d elementor-widget elementor-widget-text-editor\" data-id=\"5591748d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>REFRIGERATOR WITH FREEZER<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-93b7ec8 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"93b7ec8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7b51ad3\" data-id=\"7b51ad3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4545e4c elementor-widget elementor-widget-image\" data-id=\"4545e4c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/Progetto-senza-titolo-1-pm1fhhj6ouqr7xqow0a5wi7gpcqh1de1m12lshg5tg.png\" title=\"Progetto senza titolo (1)\" alt=\"Progetto senza titolo (1)\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f61ca59 elementor-widget elementor-widget-text-editor\" data-id=\"f61ca59\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Change of towels and sheets*<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-9014802\" data-id=\"9014802\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30f0a84 elementor-widget elementor-widget-image\" data-id=\"30f0a84\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/Progetto-senza-titolo-5-pm1fhm8dn0x6tzjv4kbaqz0roa3b3uwpaoc16v96yc.png\" title=\"Progetto senza titolo (5)\" alt=\"Progetto senza titolo (5)\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2356ce elementor-widget elementor-widget-text-editor\" data-id=\"d2356ce\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Cot, high chair and stroller**<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-e005c99\" data-id=\"e005c99\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-659e645 elementor-widget elementor-widget-image\" data-id=\"659e645\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/Progetto-senza-titolo-3-pm1fhaybd0hqyo08yffrx1v8jnmwjhnx94i7fjpx10.png\" title=\"Progetto senza titolo (3)\" alt=\"Progetto senza titolo (3)\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dcc46eb elementor-widget elementor-widget-text-editor\" data-id=\"dcc46eb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Beach kit*<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-4d0be1e\" data-id=\"4d0be1e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96c4a60 elementor-widget elementor-widget-image\" data-id=\"96c4a60\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/Progetto-senza-titolo-2-pm1fhctzqokblvxing9121e5qfdmyvvdxdt6e3n4ok.png\" title=\"Progetto senza titolo (2)\" alt=\"Progetto senza titolo (2)\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2652e1f elementor-widget elementor-widget-text-editor\" data-id=\"2652e1f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>PETS WELCOME*<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-bdb8841\" data-id=\"bdb8841\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d72a60 elementor-widget elementor-widget-image\" data-id=\"9d72a60\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/Progetto-senza-titolo-4-pk9rvl983tcbfajenu69uk94pqd7gigj7cpnoxwho4.png\" title=\"Progetto senza titolo (4)\" alt=\"Progetto senza titolo (4)\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-025ba64 elementor-widget elementor-widget-text-editor\" data-id=\"025ba64\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>iron and ironing board**<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9b7a611 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"9b7a611\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9a72001\" data-id=\"9a72001\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a6bee7 elementor-heading-tablet__align-center animated-fast elementor-heading__align-center elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3a6bee7\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">*additional paid service<br>**on request<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab03359 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"ab03359\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9a29d1b\" data-id=\"9a29d1b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65d5867 elementor-heading__align-center elementor-widget elementor-widget-heading\" data-id=\"65d5867\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">REQUEST AVAILABILITY FOR<br>\nRESIDENCE IL BORGO<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3dd3520 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"3dd3520\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fe4d75d\" data-id=\"fe4d75d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d84ebaa elementor-widget elementor-widget-text-editor\" data-id=\"d84ebaa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f7410-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/7582#wpcf7-f7410-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"7410\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.5.6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f7410-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<div class=\"row\">\n<div class=\"col-sm-6\">\n<div class=\"mb-3\"><span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name and Surname\" \/><\/span> <\/div>\n<\/div>\n<div class=\"col-sm-6\">\n<div class=\"mb-3\"><span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" \/><\/span> <\/div>\n<\/div>\n<div class=\"col-sm-6\">\n<div class=\"mb-3\"><span class=\"wpcf7-form-control-wrap prefix\"><select name=\"prefix\" class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><option value=\"Afghanistan +93\">Afghanistan +93<\/option><option value=\"Alaska +1\">Alaska +1<\/option><option value=\"Albania +355\">Albania +355<\/option><option value=\"Algeria +213\">Algeria +213<\/option><option value=\"Andorra +376\">Andorra +376<\/option><option value=\"Angola +244\">Angola +244<\/option><option value=\"Anguilla +1 264\">Anguilla +1 264<\/option><option value=\"Antigua e Barbuda +1 268\">Antigua e Barbuda +1 268<\/option><option value=\"Antille Olandesi +599\">Antille Olandesi +599<\/option><option value=\"Arabia Saudita +966\">Arabia Saudita +966<\/option><option value=\"Argentina +54\">Argentina +54<\/option><option value=\"Armenia +374\">Armenia +374<\/option><option value=\"Aruba +297\">Aruba +297<\/option><option value=\"Ascensione +247\">Ascensione +247<\/option><option value=\"Australia +61\">Australia +61<\/option><option value=\"Australia Antartic +67210-1-2\">Australia Antartic +67210-1-2<\/option><option value=\"Austria +43\">Austria +43<\/option><option value=\"Azerbaigian +994\">Azerbaigian +994<\/option><option value=\"Bahamas +1 242\">Bahamas +1 242<\/option><option value=\"Bahrein +973\">Bahrein +973<\/option><option value=\"Bangladesh +880\">Bangladesh +880<\/option><option value=\"Barbados +1 246\">Barbados +1 246<\/option><option value=\"Belgio +32\">Belgio +32<\/option><option value=\"Belize +501\">Belize +501<\/option><option value=\"Benin +229\">Benin +229<\/option><option value=\"Bermuda +1 441\">Bermuda +1 441<\/option><option value=\"Bhutan +975\">Bhutan +975<\/option><option value=\"Bielorussia +375\">Bielorussia +375<\/option><option value=\"Bolivia +591\">Bolivia +591<\/option><option value=\"Bosnia Erzegovina +387\">Bosnia Erzegovina +387<\/option><option value=\"Botswana +267\">Botswana +267<\/option><option value=\"Brasile +55\">Brasile +55<\/option><option value=\"Brunei +673\">Brunei +673<\/option><option value=\"Bulgaria +359\">Bulgaria +359<\/option><option value=\"Burkina Faso +226\">Burkina Faso +226<\/option><option value=\"Burundi +257\">Burundi +257<\/option><option value=\"Cambogia +855\">Cambogia +855<\/option><option value=\"Camerun +237\">Camerun +237<\/option><option value=\"Canada +1\">Canada +1<\/option><option value=\"Capo Verde +238\">Capo Verde +238<\/option><option value=\"Ciad +235\">Ciad +235<\/option><option value=\"Cile +56\">Cile +56<\/option><option value=\"Cina +86\">Cina +86<\/option><option value=\"Cipro +357\">Cipro +357<\/option><option value=\"Colombia +57\">Colombia +57<\/option><option value=\"Comore +269\">Comore +269<\/option><option value=\"Congo +242\">Congo +242<\/option><option value=\"Cook +682\">Cook +682<\/option><option value=\"Corea del Nord +850\">Corea del Nord +850<\/option><option value=\"Corea del Sud +82\">Corea del Sud +82<\/option><option value=\"Costa d\u2019Avorio +225\">Costa d\u2019Avorio +225<\/option><option value=\"Costarica +506\">Costarica +506<\/option><option value=\"Croazia +385\">Croazia +385<\/option><option value=\"Cuba +53\">Cuba +53<\/option><option value=\"Danimarca +45\">Danimarca +45<\/option><option value=\"Diego Garcia +246\">Diego Garcia +246<\/option><option value=\"Dominica +1 767\">Dominica +1 767<\/option><option value=\"Ecuador +593\">Ecuador +593<\/option><option value=\"Egitto +20\">Egitto +20<\/option><option value=\"El Salvador +503\">El Salvador +503<\/option><option value=\"Emirati Arabi Uniti +971\">Emirati Arabi Uniti +971<\/option><option value=\"Eritrea +291\">Eritrea +291<\/option><option value=\"Estonia +372\">Estonia +372<\/option><option value=\"Etiopia +251\">Etiopia +251<\/option><option value=\"Federazione Russa +7\">Federazione Russa +7<\/option><option value=\"Figi +679\">Figi +679<\/option><option value=\"Filippine +63\">Filippine +63<\/option><option value=\"Finlandia +358\">Finlandia +358<\/option><option value=\"Francia +33\">Francia +33<\/option><option value=\"Gabon +241\">Gabon +241<\/option><option value=\"Gambia +220\">Gambia +220<\/option><option value=\"Georgia +995\">Georgia +995<\/option><option value=\"Germania +49\">Germania +49<\/option><option value=\"Ghana +233\">Ghana +233<\/option><option value=\"Giamaica +1 876\">Giamaica +1 876<\/option><option value=\"Giappone +81\">Giappone +81<\/option><option value=\"Gibilterra +350\">Gibilterra +350<\/option><option value=\"Gibuti +253\">Gibuti +253<\/option><option value=\"Giordania +962\">Giordania +962<\/option><option value=\"Gran Bretagna +44\">Gran Bretagna +44<\/option><option value=\"Grecia +30\">Grecia +30<\/option><option value=\"Grenada +1 473\">Grenada +1 473<\/option><option value=\"Groenlandia +299\">Groenlandia +299<\/option><option value=\"Guadalupa +590\">Guadalupa +590<\/option><option value=\"Guam +671\">Guam +671<\/option><option value=\"Guatemala +502\">Guatemala +502<\/option><option value=\"Guinea +224\">Guinea +224<\/option><option value=\"Guinea Bissau +245\">Guinea Bissau +245<\/option><option value=\"Guinea Ecuatoriale +240\">Guinea Ecuatoriale +240<\/option><option value=\"Guyana +592\">Guyana +592<\/option><option value=\"Guyana Francese +594\">Guyana Francese +594<\/option><option value=\"Haiti +509\">Haiti +509<\/option><option value=\"Honduras +504\">Honduras +504<\/option><option value=\"Hong Kong +852\">Hong Kong +852<\/option><option value=\"India +91\">India +91<\/option><option value=\"Indonesia +62\">Indonesia +62<\/option><option value=\"Iran +98\">Iran +98<\/option><option value=\"Iraq +964\">Iraq +964<\/option><option value=\"Irlanda +353\">Irlanda +353<\/option><option value=\"Islanda +354\">Islanda +354<\/option><option value=\"Isole Cayman +1 345\">Isole Cayman +1 345<\/option><option value=\"Isole Falkland +500\">Isole Falkland +500<\/option><option value=\"Isole F\u00e6r Oer +298\">Isole F\u00e6r Oer +298<\/option><option value=\"Isole Marianne +670\">Isole Marianne +670<\/option><option value=\"Isole Marshall +692\">Isole Marshall +692<\/option><option value=\"Isole Norfolk +672\">Isole Norfolk +672<\/option><option value=\"Isole Salomone +677\">Isole Salomone +677<\/option><option value=\"Isole Vergini (GBR) +1 284\">Isole Vergini (GBR) +1 284<\/option><option value=\"Isole Vergini (U.S.) +1 340\">Isole Vergini (U.S.) +1 340<\/option><option value=\"Israele +972\">Israele +972<\/option><option value=\"Italia +39\">Italia +39<\/option><option value=\"Kazakistan +996\">Kazakistan +996<\/option><option value=\"Kenia +254\">Kenia +254<\/option><option value=\"Kirghizstan +996\">Kirghizstan +996<\/option><option value=\"Kiribati +686\">Kiribati +686<\/option><option value=\"Kuwait +965\">Kuwait +965<\/option><option value=\"Laos +856\">Laos +856<\/option><option value=\"Lesotho +266\">Lesotho +266<\/option><option value=\"Lettonia +371\">Lettonia +371<\/option><option value=\"Libano +961\">Libano +961<\/option><option value=\"Liberia +231\">Liberia +231<\/option><option value=\"Libia +218\">Libia +218<\/option><option value=\"Liechtenstein +423\">Liechtenstein +423<\/option><option value=\"Lituania +370\">Lituania +370<\/option><option value=\"Lussemburgo +352\">Lussemburgo +352<\/option><option value=\"Macao +853\">Macao +853<\/option><option value=\"Macedonia +389\">Macedonia +389<\/option><option value=\"Madagascar +261\">Madagascar +261<\/option><option value=\"Malawi +265\">Malawi +265<\/option><option value=\"Maldive +960\">Maldive +960<\/option><option value=\"Malesia +60\">Malesia +60<\/option><option value=\"Mali +223\">Mali +223<\/option><option value=\"Malta +356\">Malta +356<\/option><option value=\"Marocco +212\">Marocco +212<\/option><option value=\"Martinica +596\">Martinica +596<\/option><option value=\"Mauritania +222\">Mauritania +222<\/option><option value=\"Mauritius +230\">Mauritius +230<\/option><option value=\"Messico +52\">Messico +52<\/option><option value=\"Moldavia +373\">Moldavia +373<\/option><option value=\"Monaco (Principato di) +377\">Monaco (Principato di) +377<\/option><option value=\"Mongolia +976\">Mongolia +976<\/option><option value=\"Montserrat +1 664\">Montserrat +1 664<\/option><option value=\"Mozambico +258\">Mozambico +258<\/option><option value=\"Namibia +264\">Namibia +264<\/option><option value=\"Nepal +977\">Nepal +977<\/option><option value=\"Nicaragua +505\">Nicaragua +505<\/option><option value=\"Nigeria +234\">Nigeria +234<\/option><option value=\"Niue +683\">Niue +683<\/option><option value=\"Norvegia +47\">Norvegia +47<\/option><option value=\"Nuova Caledonia +687\">Nuova Caledonia +687<\/option><option value=\"Nuova Zelanda +64\">Nuova Zelanda +64<\/option><option value=\"Oman +968\">Oman +968<\/option><option value=\"Paesi Bassi (Olanda) +31\">Paesi Bassi (Olanda) +31<\/option><option value=\"Pakistan +92\">Pakistan +92<\/option><option value=\"Palau +680\">Palau +680<\/option><option value=\"Panama +507\">Panama +507<\/option><option value=\"Papua Nuova Guinea +675\">Papua Nuova Guinea +675<\/option><option value=\"Paraguay +595\">Paraguay +595<\/option><option value=\"Per\u00f9 +51\">Per\u00f9 +51<\/option><option value=\"Polinesia Francese +689\">Polinesia Francese +689<\/option><option value=\"Polonia +48\">Polonia +48<\/option><option value=\"Portogallo +351\">Portogallo +351<\/option><option value=\"Porto Rico +1 787\">Porto Rico +1 787<\/option><option value=\"Qatar +974\">Qatar +974<\/option><option value=\"Rep. Ceca +420\">Rep. Ceca +420<\/option><option value=\"Rep. Centrafrica +236\">Rep. Centrafrica +236<\/option><option value=\"Rep. Democratica del Congo +243\">Rep. Democratica del Congo +243<\/option><option value=\"Rep. Dominicana +1\">Rep. Dominicana +1<\/option><option value=\"Reunion (Francia) +262\">Reunion (Francia) +262<\/option><option value=\"Romania +40\">Romania +40<\/option><option value=\"Ruanda +250\">Ruanda +250<\/option><option value=\"Saint Elena +290\">Saint Elena +290<\/option><option value=\"Saint Kitts e Nevis +1 869\">Saint Kitts e Nevis +1 869<\/option><option value=\"Saint Pierre e Miquelon +508\">Saint Pierre e Miquelon +508<\/option><option value=\"Saint Vincent +1 784\">Saint Vincent +1 784<\/option><option value=\"Samoa Americane +684\">Samoa Americane +684<\/option><option value=\"Samoa Occidentale +685\">Samoa Occidentale +685<\/option><option value=\"Santa Lucia +1 758\">Santa Lucia +1 758<\/option><option value=\"Sao Tom\u00e8 e Principe +239\">Sao Tom\u00e8 e Principe +239<\/option><option value=\"Senegal +221\">Senegal +221<\/option><option value=\"Seychelles +248\">Seychelles +248<\/option><option value=\"Sierra Leone +232\">Sierra Leone +232<\/option><option value=\"Singapore +65\">Singapore +65<\/option><option value=\"Siria +963\">Siria +963<\/option><option value=\"Slovacchia +421\">Slovacchia +421<\/option><option value=\"Slovenia +386\">Slovenia +386<\/option><option value=\"Somalia +252\">Somalia +252<\/option><option value=\"Spagna +34\">Spagna +34<\/option><option value=\"Sri Lanka +94\">Sri Lanka +94<\/option><option value=\"Sudafrica +27\">Sudafrica +27<\/option><option value=\"Sudan +249\">Sudan +249<\/option><option value=\"Svezia +46\">Svezia +46<\/option><option value=\"Svizzera +41\">Svizzera +41<\/option><option value=\"Swaziland +268\">Swaziland +268<\/option><option value=\"Tajikistan +737\">Tajikistan +737<\/option><option value=\"Taiwan +886\">Taiwan +886<\/option><option value=\"Tanzania +255\">Tanzania +255<\/option><option value=\"Thailandia +66\">Thailandia +66<\/option><option value=\"Togo +228\">Togo +228<\/option><option value=\"Tonga +676\">Tonga +676<\/option><option value=\"Trinidad e Tobago +1 868\">Trinidad e Tobago +1 868<\/option><option value=\"Tunisia +216\">Tunisia +216<\/option><option value=\"Turchia +90\">Turchia +90<\/option><option value=\"Turkmenistan +993\">Turkmenistan +993<\/option><option value=\"Turks e Caicos +1 649\">Turks e Caicos +1 649<\/option><option value=\"Tuvalu +688\">Tuvalu +688<\/option><option value=\"Ucraina +380\">Ucraina +380<\/option><option value=\"Uganda +256\">Uganda +256<\/option><option value=\"Ungheria +36\">Ungheria +36<\/option><option value=\"Uruguay +598\">Uruguay +598<\/option><option value=\"USA +1\">USA +1<\/option><option value=\"Uzbekistan +998\">Uzbekistan +998<\/option><option value=\"Vanuato +678\">Vanuato +678<\/option><option value=\"Venezuela +58\">Venezuela +58<\/option><option value=\"Vietnam +84\">Vietnam +84<\/option><option value=\"Wallis e Futuna +681\">Wallis e Futuna +681<\/option><option value=\"Yemen +967\">Yemen +967<\/option><option value=\"Yugoslavia +381\">Yugoslavia +381<\/option><option value=\"Zambia +260\">Zambia +260<\/option><option value=\"Zimbabwe +263\">Zimbabwe +263<\/option><\/select><\/span><\/div>\n<\/div>\n<div class=\"col-sm-6\">\n<div class=\"mb-3\"><span class=\"wpcf7-form-control-wrap telefono\"><input type=\"text\" name=\"telefono\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone\" \/><\/span> <\/div>\n<\/div>\n<div class=\"col-sm-6\">\n<div class=\"mb-3\"><label>Arrival Date<\/label><span class=\"wpcf7-form-control-wrap your-date\"><input type=\"date\" name=\"your-date\" value=\"\" class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Arrivo\" \/><\/span><\/div>\n<\/div>\n<div class=\"col-sm-6\">\n<div class=\"mb-3\"><label>Departure Date<\/label><span class=\"wpcf7-form-control-wrap your-date2\"><input type=\"date\" name=\"your-date2\" value=\"\" class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Partenza\" \/><\/span> <\/div>\n<\/div>\n<div class=\"col-sm-6\">\n<div class=\"mb-3\"<span class=\"wpcf7-form-control-wrap Adulti\"><select name=\"Adulti\" class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><option value=\"\">Adults<\/option><option value=\"1\">1<\/option><option value=\"2\">2<\/option><option value=\"3\">3<\/option><option value=\"4\">4<\/option><option value=\"5\">5<\/option><option value=\"6\">6<\/option><\/select><\/span><\/div>\n<\/div>\n<div class=\"col-sm-6\">\n<div class=\"mb-3\"<span class=\"wpcf7-form-control-wrap Bambini\"><select name=\"Bambini\" class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><option value=\"\">Children<\/option><option value=\"1\">1<\/option><option value=\"2\">2<\/option><option value=\"3\">3<\/option><option value=\"4\">4<\/option><option value=\"5\">5<\/option><option value=\"6\">6<\/option><\/select><\/span><\/div>\n<\/div>\n<div class=\"col-sm-12\">\n<div class=\"mb-3 text-left\"><span class=\"wpcf7-form-control-wrap textarea-203\"><textarea name=\"textarea-203\" cols=\"40\" rows=\"3\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Indicate the age of the children and specific needs\"><\/textarea><\/span> <\/div>\n<\/div>\n<div class=\"col-sm-12\">\n<div class=\"mb-3 text-left\" style=\"color:black\"><span class=\"wpcf7-form-control-wrap checkbox-336\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"checkbox-336[]\" value=\"I have read and accept the Privacy Policy.\" \/><span class=\"wpcf7-list-item-label\">I have read and accept the Privacy Policy.<\/span><\/span><\/span><\/span> <\/p>\n<div class=\"mb-3 text-left\" style=\"color:black\"><span class=\"wpcf7-form-control-wrap checkbox-337\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"checkbox-337[]\" value=\"I agree to receive commercial communications.\" \/><span class=\"wpcf7-list-item-label\">I agree to receive commercial communications.<\/span><\/span><\/span><\/span> <\/div>\n<\/div>\n<div class=\"col-sm-12\">\n<div class=\"\"><input type=\"submit\" value=\"REQUEST AVAILABILITY\" class=\"wpcf7-form-control has-spinner wpcf7-submit w-100 button-lg\" \/><\/div>\n<\/div>\n<\/div>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8afdb4 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"c8afdb4\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-015fe74\" data-id=\"015fe74\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d1ed1c elementor-heading-tablet__align-center animated-fast elementor-heading__align-center elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2d1ed1c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DISCOVER OTHER TYPOLOGIES<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac88cd5 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"ac88cd5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4062278\" data-id=\"4062278\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-6ed1c10 elementor-section-full_width elementor-section-height-min-height elementor-section-content-bottom elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"6ed1c10\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a78ffd1\" data-id=\"a78ffd1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe98526 animated-fast elementor-heading__align-left elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"fe98526\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-xxl\"><a href=\"https:\/\/www.sardegnasummer.it\/en\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-turquoise-residence-il-borgo\/\">Turquoise<\/a><\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>APARTMENT bluette residence il borgo &#8211; porto san paolo Precedente Successivo Comfort and luxury in the center of Porto San Paolo Il Borgo di Porto San Paolo simply don\u2019t come any finer. Settled in the heart of this beautiful neighbourhood, this apartment is loved for its winning combination of elegance and luxury decoration inspired by &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.sardegnasummer.it\/en\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-bluette-residence-il-borgo\/\" class=\"more-link\">Read More <span class=\"screen-reader-text\"> &#8220;Apartment Bluette Residence Il Borgo&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":7324,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7582","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Apartment Bluette Residence Il Borgo - SardegnaSummer.it<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-bluette-residence-il-borgo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apartment Bluette Residence Il Borgo - SardegnaSummer.it\" \/>\n<meta property=\"og:description\" content=\"APARTMENT bluette residence il borgo &#8211; porto san paolo Precedente Successivo Comfort and luxury in the center of Porto San Paolo Il Borgo di Porto San Paolo simply don\u2019t come any finer. Settled in the heart of this beautiful neighbourhood, this apartment is loved for its winning combination of elegance and luxury decoration inspired by &hellip; Read More &quot;Apartment Bluette Residence Il Borgo&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-bluette-residence-il-borgo\/\" \/>\n<meta property=\"og:site_name\" content=\"SardegnaSummer.it\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-23T09:31:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/IL-BORGO-PSP9-scaled-pk0e35khglgztbyhkj7qi7n3wn70kq2r0tuiow70kw.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.sardegnasummer.it\/#organization\",\"name\":\"Sardegna Summer\",\"url\":\"https:\/\/www.sardegnasummer.it\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.sardegnasummer.it\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2018\/12\/logo3-1.png\",\"contentUrl\":\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2018\/12\/logo3-1.png\",\"width\":261,\"height\":135,\"caption\":\"Sardegna Summer\"},\"image\":{\"@id\":\"https:\/\/www.sardegnasummer.it\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sardegnasummer.it\/#website\",\"url\":\"https:\/\/www.sardegnasummer.it\/\",\"name\":\"SardegnaSummer.it\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.sardegnasummer.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sardegnasummer.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-bluette-residence-il-borgo\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/IL-BORGO-PSP9-scaled-pk0e35khglgztbyhkj7qi7n3wn70kq2r0tuiow70kw.jpg\",\"contentUrl\":\"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/IL-BORGO-PSP9-scaled-pk0e35khglgztbyhkj7qi7n3wn70kq2r0tuiow70kw.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-bluette-residence-il-borgo\/#webpage\",\"url\":\"https:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-bluette-residence-il-borgo\/\",\"name\":\"Apartment Bluette Residence Il Borgo - SardegnaSummer.it\",\"isPartOf\":{\"@id\":\"https:\/\/www.sardegnasummer.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-bluette-residence-il-borgo\/#primaryimage\"},\"datePublished\":\"2022-02-04T09:18:20+00:00\",\"dateModified\":\"2025-06-23T09:31:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-bluette-residence-il-borgo\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-bluette-residence-il-borgo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-bluette-residence-il-borgo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.sardegnasummer.it\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IL BORGO Porto San Paolo\",\"item\":\"https:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Apartment Bluette Residence Il Borgo\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apartment Bluette Residence Il Borgo - SardegnaSummer.it","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-bluette-residence-il-borgo\/","og_locale":"en_US","og_type":"article","og_title":"Apartment Bluette Residence Il Borgo - SardegnaSummer.it","og_description":"APARTMENT bluette residence il borgo &#8211; porto san paolo Precedente Successivo Comfort and luxury in the center of Porto San Paolo Il Borgo di Porto San Paolo simply don\u2019t come any finer. Settled in the heart of this beautiful neighbourhood, this apartment is loved for its winning combination of elegance and luxury decoration inspired by &hellip; Read More \"Apartment Bluette Residence Il Borgo\"","og_url":"https:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-bluette-residence-il-borgo\/","og_site_name":"SardegnaSummer.it","article_modified_time":"2025-06-23T09:31:14+00:00","og_image":[{"url":"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/IL-BORGO-PSP9-scaled-pk0e35khglgztbyhkj7qi7n3wn70kq2r0tuiow70kw.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.sardegnasummer.it\/#organization","name":"Sardegna Summer","url":"https:\/\/www.sardegnasummer.it\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/www.sardegnasummer.it\/#logo","inLanguage":"en-US","url":"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2018\/12\/logo3-1.png","contentUrl":"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/2018\/12\/logo3-1.png","width":261,"height":135,"caption":"Sardegna Summer"},"image":{"@id":"https:\/\/www.sardegnasummer.it\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.sardegnasummer.it\/#website","url":"https:\/\/www.sardegnasummer.it\/","name":"SardegnaSummer.it","description":"","publisher":{"@id":"https:\/\/www.sardegnasummer.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sardegnasummer.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-bluette-residence-il-borgo\/#primaryimage","inLanguage":"en-US","url":"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/IL-BORGO-PSP9-scaled-pk0e35khglgztbyhkj7qi7n3wn70kq2r0tuiow70kw.jpg","contentUrl":"https:\/\/www.sardegnasummer.it\/wp-content\/uploads\/elementor\/thumbs\/IL-BORGO-PSP9-scaled-pk0e35khglgztbyhkj7qi7n3wn70kq2r0tuiow70kw.jpg"},{"@type":"WebPage","@id":"https:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-bluette-residence-il-borgo\/#webpage","url":"https:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-bluette-residence-il-borgo\/","name":"Apartment Bluette Residence Il Borgo - SardegnaSummer.it","isPartOf":{"@id":"https:\/\/www.sardegnasummer.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-bluette-residence-il-borgo\/#primaryimage"},"datePublished":"2022-02-04T09:18:20+00:00","dateModified":"2025-06-23T09:31:14+00:00","breadcrumb":{"@id":"https:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-bluette-residence-il-borgo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-bluette-residence-il-borgo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/appartamento-bluette-residence-il-borgo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sardegnasummer.it\/es\/"},{"@type":"ListItem","position":2,"name":"IL BORGO Porto San Paolo","item":"https:\/\/www.sardegnasummer.it\/residence-case-affitto-porto-san-paolo-sardegna\/"},{"@type":"ListItem","position":3,"name":"Apartment Bluette Residence Il Borgo"}]}]}},"_links":{"self":[{"href":"https:\/\/www.sardegnasummer.it\/en\/wp-json\/wp\/v2\/pages\/7582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sardegnasummer.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sardegnasummer.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sardegnasummer.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sardegnasummer.it\/en\/wp-json\/wp\/v2\/comments?post=7582"}],"version-history":[{"count":14,"href":"https:\/\/www.sardegnasummer.it\/en\/wp-json\/wp\/v2\/pages\/7582\/revisions"}],"predecessor-version":[{"id":396981,"href":"https:\/\/www.sardegnasummer.it\/en\/wp-json\/wp\/v2\/pages\/7582\/revisions\/396981"}],"up":[{"embeddable":true,"href":"https:\/\/www.sardegnasummer.it\/en\/wp-json\/wp\/v2\/pages\/7324"}],"wp:attachment":[{"href":"https:\/\/www.sardegnasummer.it\/en\/wp-json\/wp\/v2\/media?parent=7582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}